{"id":1630,"date":"2021-05-20T13:49:48","date_gmt":"2021-05-20T11:49:48","guid":{"rendered":"https:\/\/www.proyectohombreprovinciacadiz.org\/?p=1630"},"modified":"2021-05-20T13:49:49","modified_gmt":"2021-05-20T11:49:49","slug":"donativo-de-la-asociacion-de-reyes-magos-de-jerez","status":"publish","type":"post","link":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/2021\/05\/20\/donativo-de-la-asociacion-de-reyes-magos-de-jerez\/","title":{"rendered":"Donativo de la Asociaci\u00f3n de Reyes Magos de Jerez"},"content":{"rendered":"\n<p>Un a\u00f1o m\u00e1s, la Asociaci\u00f3n de Reyes Magos de Jerez ha colaborado con nosotros con una ayuda econ\u00f3mica gracias a la Campa\u00f1a realizada este a\u00f1o.<\/p>\n\n\n\n<p>El acto, celebrado el 14 de mayo en el sal\u00f3n de actos de Cajasol,&nbsp;&nbsp;estuvo presidido por Mamen S\u00e1nchez, alcaldesa de Jerez, con la presencia de Gemma Garc\u00eda Berm\u00fadez, presidenta de la Asociaci\u00f3n, asistiendo Luis Bononato en representaci\u00f3n de P. Hombre.<\/p>\n\n\n\n<p>Nuestro agradecimiento a la Asociaci\u00f3n y m\u00e1s en este a\u00f1o que tan dif\u00edcil ha sido la Campa\u00f1a de Reyes debido a la pandemia de la COVID 19<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un a\u00f1o m\u00e1s, la Asociaci\u00f3n de Reyes Magos de Jerez ha colaborado con nosotros con una ayuda econ\u00f3mica gracias a la Campa\u00f1a realizada este a\u00f1o. El acto, celebrado el 14 de mayo en el sal\u00f3n de actos de Cajasol,&nbsp;&nbsp;estuvo presidido por Mamen S\u00e1nchez, alcaldesa de Jerez, con la presencia de Gemma Garc\u00eda Berm\u00fadez, presidenta de &#8230; <a title=\"Donativo de la Asociaci\u00f3n de Reyes Magos de Jerez\" class=\"read-more\" href=\"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/2021\/05\/20\/donativo-de-la-asociacion-de-reyes-magos-de-jerez\/\" aria-label=\"M\u00e1s en Donativo de la Asociaci\u00f3n de Reyes Magos de Jerez\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1630","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/wp-json\/wp\/v2\/posts\/1630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/wp-json\/wp\/v2\/comments?post=1630"}],"version-history":[{"count":1,"href":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/wp-json\/wp\/v2\/posts\/1630\/revisions"}],"predecessor-version":[{"id":1632,"href":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/wp-json\/wp\/v2\/posts\/1630\/revisions\/1632"}],"wp:attachment":[{"href":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/wp-json\/wp\/v2\/media?parent=1630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/wp-json\/wp\/v2\/categories?post=1630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proyectohombreprovinciacadiz.org\/index.php\/wp-json\/wp\/v2\/tags?post=1630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}